{"id":6062,"date":"2025-04-29T05:23:12","date_gmt":"2025-04-29T05:23:12","guid":{"rendered":"https:\/\/clickeventos.cl\/?page_id=6062"},"modified":"2025-05-09T17:10:37","modified_gmt":"2025-05-09T17:10:37","slug":"detalles-con-delivery","status":"publish","type":"page","link":"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/","title":{"rendered":"Detalles con Delivery"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"section-title style-1 text-left text-small \">\n\t\t\t\t<div class=\"title\" >El detalle perfecto, hecho a tu medida.<\/div>\n\t\t\t<\/div>[vc_cta h2=\u00bb\u00bb style=\u00bbflat\u00bb color=\u00bbblack\u00bb css=\u00bb\u00bb]En Click Eventos transformamos cualquier ocasi\u00f3n en un momento especial con nuestros desayunos y tablas de regalo personalizadas. Son tem\u00e1ticas, creativas y 100% ajustadas a lo que la persona celebra o necesita.<br \/>\n<strong>\u00bfUn desayuno especial para el D\u00eda de la Madre? \u00bfUna tabla con Fernet para despedir las vacaciones?<\/strong> T\u00fa eliges el concepto, y nosotros nos encargamos del resto: productos deliciosos, decoraci\u00f3n cuidada y entrega a domicilio. Ideal para empresas que quieren sorprender a sus colaboradores, o para dar ese toque personal en fechas especiales.[\/vc_cta][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-6161\"><form id=\"wpforms-form-6161\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"6161\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/6062\" data-token=\"0f009481421e07ff874338a11470eeed\" data-token-time=\"1784134665\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-6161-field_6-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-6161-field_6\">Comente aqu\u00ed las caracter\u00edsticas de su evento<\/label><textarea id=\"wpforms-6161-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-6161-field_6-error\" aria-describedby=\"wpforms-6161-field_6-description\" ><\/textarea><div id=\"wpforms-6161-field_6-description\" class=\"wpforms-field-description\">Ingrese aqu\u00ed su descripci\u00f3n<\/div><\/div><div id=\"wpforms-6161-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-6161-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-6161-field_1-error\" required><label for=\"wpforms-6161-field_1\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-6161-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-6161-field_1-last-error\" required><label for=\"wpforms-6161-field_1-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-6161-field_7-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-6161-field_7\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-6161-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" spellcheck=\"false\" aria-errormessage=\"wpforms-6161-field_7-error\" required><\/div><div id=\"wpforms-6161-field_12-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-6161-field_12\">Fono <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-6161-field_12\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][12]\" step=\"any\" aria-errormessage=\"wpforms-6161-field_12-error\" required><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"6161\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/clickeventos.cl\/index.php\/wp-json\/wp\/v2\/pages\/6062\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-6161\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/clickeventos.cl\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_cta h2=\u00bb\u00bb style=\u00bbflat\u00bb color=\u00bbblack\u00bb css=\u00bb\u00bb]En Click Eventos transformamos cualquier ocasi\u00f3n en un momento especial con nuestros desayunos y tablas de regalo personalizadas. Son tem\u00e1ticas, creativas y 100% ajustadas a lo&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6062","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Detalles con Delivery - Click Eventos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detalles con Delivery - Click Eventos\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_cta h2=\u00bb\u00bb style=\u00bbflat\u00bb color=\u00bbblack\u00bb css=\u00bb\u00bb]En Click Eventos transformamos cualquier ocasi\u00f3n en un momento especial con nuestros desayunos y tablas de regalo personalizadas. Son tem\u00e1ticas, creativas y 100% ajustadas a lo&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/\" \/>\n<meta property=\"og:site_name\" content=\"Click Eventos\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T17:10:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/\",\"url\":\"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/\",\"name\":\"Detalles con Delivery - Click Eventos\",\"isPartOf\":{\"@id\":\"https:\/\/clickeventos.cl\/#website\"},\"datePublished\":\"2025-04-29T05:23:12+00:00\",\"dateModified\":\"2025-05-09T17:10:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/clickeventos.cl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detalles con Delivery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/clickeventos.cl\/#website\",\"url\":\"https:\/\/clickeventos.cl\/\",\"name\":\"Click Eventos\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/clickeventos.cl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detalles con Delivery - Click Eventos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/","og_locale":"es_ES","og_type":"article","og_title":"Detalles con Delivery - Click Eventos","og_description":"[vc_row][vc_column][vc_cta h2=\u00bb\u00bb style=\u00bbflat\u00bb color=\u00bbblack\u00bb css=\u00bb\u00bb]En Click Eventos transformamos cualquier ocasi\u00f3n en un momento especial con nuestros desayunos y tablas de regalo personalizadas. Son tem\u00e1ticas, creativas y 100% ajustadas a lo&hellip;","og_url":"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/","og_site_name":"Click Eventos","article_modified_time":"2025-05-09T17:10:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/","url":"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/","name":"Detalles con Delivery - Click Eventos","isPartOf":{"@id":"https:\/\/clickeventos.cl\/#website"},"datePublished":"2025-04-29T05:23:12+00:00","dateModified":"2025-05-09T17:10:37+00:00","breadcrumb":{"@id":"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/clickeventos.cl\/index.php\/detalles-con-delivery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clickeventos.cl\/"},{"@type":"ListItem","position":2,"name":"Detalles con Delivery"}]},{"@type":"WebSite","@id":"https:\/\/clickeventos.cl\/#website","url":"https:\/\/clickeventos.cl\/","name":"Click Eventos","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clickeventos.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/clickeventos.cl\/index.php\/wp-json\/wp\/v2\/pages\/6062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clickeventos.cl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clickeventos.cl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clickeventos.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clickeventos.cl\/index.php\/wp-json\/wp\/v2\/comments?post=6062"}],"version-history":[{"count":3,"href":"https:\/\/clickeventos.cl\/index.php\/wp-json\/wp\/v2\/pages\/6062\/revisions"}],"predecessor-version":[{"id":6165,"href":"https:\/\/clickeventos.cl\/index.php\/wp-json\/wp\/v2\/pages\/6062\/revisions\/6165"}],"wp:attachment":[{"href":"https:\/\/clickeventos.cl\/index.php\/wp-json\/wp\/v2\/media?parent=6062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}